{"id":6511,"date":"2016-11-14T11:23:25","date_gmt":"2016-11-14T10:23:25","guid":{"rendered":"http:\/\/www.stve.fr\/Actu\/?p=6511"},"modified":"2016-11-14T11:23:25","modified_gmt":"2016-11-14T10:23:25","slug":"le-renouveau-du-beaujolais-nouveau","status":"publish","type":"post","link":"http:\/\/www.stve.fr\/Actu\/2016\/11\/14\/le-renouveau-du-beaujolais-nouveau\/","title":{"rendered":"Le renouveau du Beaujolais nouveau"},"content":{"rendered":"<blockquote><p>\nLe Beaujolais nouveau sera lanc\u00e9 comme chaque ann\u00e9e le 3\u00e8me jeudi de novembre.<br \/>\nLa tendance est \u00e0 des cuv\u00e9es de plus en plus qualitatives pour des moments de d\u00e9gustation (enfin) agr\u00e9ables.<\/p><\/blockquote>\n<p><!--more--><\/p>\n<p>Fraise tagada ? Banane ? Pas s\u00fbr que le jeu des pronostics ait encore lieu cette ann\u00e9e quant aux ar\u00f4mes dominants du futur Beaujolais nouveau dont la sortie est pr\u00e9vue jeudi. Pourtant, l\u2019on revient de loin car effectivement, pendant des ann\u00e9es, le Beaujolais nouveau \u00e9tait devenu une caricature de vin, pr\u00e9texte \u00e0 des soir\u00e9es conviviales mais absolument pas m\u00e9morables viniquement parlant. Apr\u00e8s cette p\u00e9riode d\u2019exc\u00e8s qui a beaucoup nui \u00e0 l\u2019image de ce vin plaisir, des vignerons ont d\u00e9cid\u00e9 de prendre leur b\u00e2ton de p\u00e8lerin avec l\u2019objectif de le faire red\u00e9couvrir aux consommateurs. Parmi ces nouveaux h\u00e9rauts se trouvent notamment les vignerons du groupement \u00ab Terroirs Originels \u00bb. Un groupe \u00ab d\u2019artisans-vignerons \u00bb comme ils se d\u00e9finissent, des terriens attach\u00e9s \u00e0 leur terroir et passionn\u00e9s par le gamay qui n\u2019est cultiv\u00e9 presque nulle part ailleurs dans le monde. Tous ont une vision convergente des vins qu\u2019ils souhaitent proposer. En un temps tr\u00e8s court (un mois s\u00e9pare la vendange de la sortie des vins), il s\u2019agit de parvenir \u00e0 proposer un vin \u00e9quilibr\u00e9, tout en fra\u00eecheur et conservant surtout le fruit \u00e9clatant que peut offrir le gamay dans sa prime jeunesse. Un challenge qui, pour le vigneron Robert Perroud, \u00ab doit \u00eatre relev\u00e9 par de bons vinificateurs car le c\u00e9page est d\u00e9licat et ne supporte pas d\u2019\u00eatre mal trait\u00e9 \u00e0 l\u2019image du pinot noir en Bourgogne \u00bb. Apr\u00e8s une mac\u00e9ration carbonique en grappes enti\u00e8res de 4 \u00e0 5 jours, les vins sont donc g\u00e9n\u00e9ralement d\u00e9cant\u00e9s \u00e0 froid pour \u00eatre clarifi\u00e9s. Point de filtration qui viendrait les bousculer trop et rendrait leur consommation peu agr\u00e9able les semaines suivantes.<\/p>\n<p><strong>Une attention particuli\u00e8re<\/strong><br \/>\nLe Beaujolais nouveau est loin d\u2019\u00eatre un sous-vin, produit uniquement pour amuser la galerie. Des vignerons y mettent du c\u0153ur, \u00e0 l\u2019instar de Lucien Lardy qui produit un Beaujolais-villages nouveau avec des vieilles vignes plant\u00e9es en 1951. Des vignes au rendement moindre mais donnant un r\u00e9sultat qualitatif plus int\u00e9ressant qui aurait tout \u00e0 fait pu \u00eatre utilis\u00e9es dans une cuv\u00e9e classique. A la d\u00e9gustation, le r\u00e9sultat est \u00e9tonnant puisque les ar\u00f4mes de fruits rouges sont flatteurs et s\u2019\u00e9panouissent avec des ar\u00f4mes de violette, le tout avec un toucher de bouche tout en densit\u00e9. D\u2019autres vignerons proposent des styles diff\u00e9rents mais tout aussi plaisants. Une diversit\u00e9 de bon aloi qui fait mentir, une fois de plus, la simplification extr\u00eame qui pr\u00e9valait autour d\u2019un pr\u00e9tendu style dominant du Beaujolais nouveau chaque ann\u00e9e. Prenez le Beaujolais villages nouveau d\u2019Emmanuel Fellot qui, l\u00e0 encore, int\u00e8gre une partie de tr\u00e8s vieilles vignes du XIX\u00e8me si\u00e8cle (les autres ont entre 25 et 70 ans). La d\u00e9licatesse fruit\u00e9e du nez n\u2019a rien \u00e0 envier \u00e0 la finesse en bouche. Un vin velout\u00e9 qui se r\u00e9v\u00e8le d\u2019une rondeur tr\u00e8s gourmande. Un vin qu\u2019Emmanuel conseille vivement de d\u00e9guster sur un fromage de ch\u00e8vre pas trop sec. On pourrait \u00e9galement citer le Beaujolais nouveau de Robert Perroud, envo\u00fbtant avec ses notes de framboise et de rose m\u00eal\u00e9es. Les exemples sont pl\u00e9thores.<\/p>\n<p>Le ph\u00e9nix Beaujolais Nouveau est bien en train de rena\u00eetre de ses cendres. Le \u00ab Beaujo \u00bb risque bien d\u2019avoir une autre saveur cette ann\u00e9e, \u00e0 condition de bien le choisir.<\/p>\n<p style=\"font-size: 10px;\">Sources : <a href=\"http:\/\/www.terredevins.com\">  Jean-Michel Brouard \/ terredevins.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Beaujolais nouveau sera lanc\u00e9 comme chaque ann\u00e9e le 3\u00e8me jeudi de novembre. La tendance est \u00e0 des cuv\u00e9es de plus en plus qualitatives pour des moments de d\u00e9gustation (enfin) agr\u00e9ables.<\/p>\n","protected":false},"author":1,"featured_media":6513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-6511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/posts\/6511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/comments?post=6511"}],"version-history":[{"count":2,"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/posts\/6511\/revisions"}],"predecessor-version":[{"id":6514,"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/posts\/6511\/revisions\/6514"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/media\/6513"}],"wp:attachment":[{"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/media?parent=6511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/categories?post=6511"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.stve.fr\/Actu\/wp-json\/wp\/v2\/tags?post=6511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}